{"id":66080,"date":"2026-05-08T11:10:12","date_gmt":"2026-05-08T11:10:12","guid":{"rendered":"https:\/\/www.teka.com\/es-uy\/producto\/in-994_539940280\/"},"modified":"2026-05-07T04:28:43","modified_gmt":"2026-05-07T05:28:43","slug":"in-994_539940280","status":"publish","type":"product","link":"https:\/\/www.teka.com\/es-uy\/producto\/in-994_539940280\/","title":{"rendered":"IN 994"},"content":{"rendered":"<ul>\n<li>Ca\u00f1o giratorio alto<\/li>\n<li>Cartucho de discos cer\u00e1micos de alta resistencia<\/li>\n<li>Aireador anti-calc\u00e1reo con limitador de caudal a 5 l\/min<\/li>\n<li>Sistema de fijaci\u00f3n r\u00e1pida Easy-Quick<\/li>\n<li>Latiguillos certificados de 1\/2\u201d de alta resistencia<\/li>\n<\/ul>\n","protected":false},"featured_media":0,"parent":0,"template":"","product_cat":[57271],"product_cleaning_system":[],"product_3rd_basket":[],"product_drawers":[],"product_type_of_installation":[57177],"product_edition":[],"product_serie":[],"product_features":[],"finishes":[],"product_bundles":[],"product_energy_efficiency":[],"product_video_training":[],"class_list":["post-66080","product","type-product","status-publish","hentry","product_cat-griferia-de-cocina","color-cromo","product_type_of_appliance-cano-alto","product_icons-anti-scale_aerator","product_icons-easy_quick","product_icons-eco","product_icons-swivel_spout","product_type_of_installation-libre-instalacion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IN 994 | Teka Uruguay<\/title>\n<meta name=\"description\" content=\"Lavavajillas integrado de Teka con clasificaci\u00f3n energ\u00e9tica A++. Capacidad: 14 cubiertos. Tercera bandeja para cubiertos. 9 programas y 6 temperaturas de lavado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.teka.com\/es-uy\/producto\/in-994_539940280\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IN 994 | Teka Uruguay\" \/>\n<meta property=\"og:description\" content=\"Lavavajillas integrado de Teka con clasificaci\u00f3n energ\u00e9tica A++. Capacidad: 14 cubiertos. Tercera bandeja para cubiertos. 9 programas y 6 temperaturas de lavado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.teka.com\/es-uy\/producto\/in-994_539940280\/\" \/>\n<meta property=\"og:site_name\" content=\"Teka Uruguay\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.teka.com\\\/es-uy\\\/producto\\\/in-994_539940280\\\/\",\"url\":\"https:\\\/\\\/www.teka.com\\\/es-uy\\\/producto\\\/in-994_539940280\\\/\",\"name\":\"IN 994 | Teka Uruguay\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.teka.com\\\/es-uy\\\/#website\"},\"datePublished\":\"2026-05-08T11:10:12+00:00\",\"description\":\"Lavavajillas integrado de Teka con clasificaci\u00f3n energ\u00e9tica A++. Capacidad: 14 cubiertos. Tercera bandeja para cubiertos. 9 programas y 6 temperaturas de lavado.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.teka.com\\\/es-uy\\\/producto\\\/in-994_539940280\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.teka.com\\\/es-uy\\\/#website\",\"url\":\"https:\\\/\\\/www.teka.com\\\/es-uy\\\/\",\"name\":\"Teka Uruguay\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.teka.com\\\/es-uy\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.teka.com\\\/es-uy\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.teka.com\\\/es-uy\\\/#organization\",\"name\":\"Teka Uruguay\",\"url\":\"https:\\\/\\\/www.teka.com\\\/es-uy\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.teka.com\\\/es-uy\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.teka.com\\\/es-uy\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2018\\\/10\\\/404-teka.png\",\"contentUrl\":\"https:\\\/\\\/www.teka.com\\\/es-uy\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2018\\\/10\\\/404-teka.png\",\"width\":200,\"height\":200,\"caption\":\"Teka Uruguay\"},\"image\":{\"@id\":\"https:\\\/\\\/www.teka.com\\\/es-uy\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IN 994 | Teka Uruguay","description":"Lavavajillas integrado de Teka con clasificaci\u00f3n energ\u00e9tica A++. Capacidad: 14 cubiertos. Tercera bandeja para cubiertos. 9 programas y 6 temperaturas de lavado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.teka.com\/es-uy\/producto\/in-994_539940280\/","og_locale":"es_ES","og_type":"article","og_title":"IN 994 | Teka Uruguay","og_description":"Lavavajillas integrado de Teka con clasificaci\u00f3n energ\u00e9tica A++. Capacidad: 14 cubiertos. Tercera bandeja para cubiertos. 9 programas y 6 temperaturas de lavado.","og_url":"https:\/\/www.teka.com\/es-uy\/producto\/in-994_539940280\/","og_site_name":"Teka Uruguay","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.teka.com\/es-uy\/producto\/in-994_539940280\/","url":"https:\/\/www.teka.com\/es-uy\/producto\/in-994_539940280\/","name":"IN 994 | Teka Uruguay","isPartOf":{"@id":"https:\/\/www.teka.com\/es-uy\/#website"},"datePublished":"2026-05-08T11:10:12+00:00","description":"Lavavajillas integrado de Teka con clasificaci\u00f3n energ\u00e9tica A++. Capacidad: 14 cubiertos. Tercera bandeja para cubiertos. 9 programas y 6 temperaturas de lavado.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.teka.com\/es-uy\/producto\/in-994_539940280\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.teka.com\/es-uy\/#website","url":"https:\/\/www.teka.com\/es-uy\/","name":"Teka Uruguay","description":"","publisher":{"@id":"https:\/\/www.teka.com\/es-uy\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.teka.com\/es-uy\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.teka.com\/es-uy\/#organization","name":"Teka Uruguay","url":"https:\/\/www.teka.com\/es-uy\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.teka.com\/es-uy\/#\/schema\/logo\/image\/","url":"https:\/\/www.teka.com\/es-uy\/wp-content\/uploads\/sites\/56\/2018\/10\/404-teka.png","contentUrl":"https:\/\/www.teka.com\/es-uy\/wp-content\/uploads\/sites\/56\/2018\/10\/404-teka.png","width":200,"height":200,"caption":"Teka Uruguay"},"image":{"@id":"https:\/\/www.teka.com\/es-uy\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.teka.com\/es-uy\/wp-json\/wp\/v2\/product\/66080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.teka.com\/es-uy\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.teka.com\/es-uy\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/www.teka.com\/es-uy\/wp-json\/wp\/v2\/media?parent=66080"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.teka.com\/es-uy\/wp-json\/wp\/v2\/product_cat?post=66080"},{"taxonomy":"product_cleaning_system","embeddable":true,"href":"https:\/\/www.teka.com\/es-uy\/wp-json\/wp\/v2\/product_cleaning_system?post=66080"},{"taxonomy":"product_3rd_basket","embeddable":true,"href":"https:\/\/www.teka.com\/es-uy\/wp-json\/wp\/v2\/product_3rd_basket?post=66080"},{"taxonomy":"product_drawers","embeddable":true,"href":"https:\/\/www.teka.com\/es-uy\/wp-json\/wp\/v2\/product_drawers?post=66080"},{"taxonomy":"product_type_of_installation","embeddable":true,"href":"https:\/\/www.teka.com\/es-uy\/wp-json\/wp\/v2\/product_type_of_installation?post=66080"},{"taxonomy":"product_edition","embeddable":true,"href":"https:\/\/www.teka.com\/es-uy\/wp-json\/wp\/v2\/product_edition?post=66080"},{"taxonomy":"product_serie","embeddable":true,"href":"https:\/\/www.teka.com\/es-uy\/wp-json\/wp\/v2\/product_serie?post=66080"},{"taxonomy":"product_features","embeddable":true,"href":"https:\/\/www.teka.com\/es-uy\/wp-json\/wp\/v2\/product_features?post=66080"},{"taxonomy":"finishes","embeddable":true,"href":"https:\/\/www.teka.com\/es-uy\/wp-json\/wp\/v2\/finishes?post=66080"},{"taxonomy":"product_bundles","embeddable":true,"href":"https:\/\/www.teka.com\/es-uy\/wp-json\/wp\/v2\/product_bundles?post=66080"},{"taxonomy":"product_energy_efficiency","embeddable":true,"href":"https:\/\/www.teka.com\/es-uy\/wp-json\/wp\/v2\/product_energy_efficiency?post=66080"},{"taxonomy":"product_video_training","embeddable":true,"href":"https:\/\/www.teka.com\/es-uy\/wp-json\/wp\/v2\/product_video_training?post=66080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}